{"id":213,"count":6,"description":"","link":"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/","name":"gourmet honey","slug":"gourmet-honey","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>gourmet honey archivos - Pico y Tallo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"gourmet honey archivos - Pico y Tallo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/\" \/>\n<meta property=\"og:site_name\" content=\"Pico y Tallo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/tag\\\/gourmet-honey\\\/\",\"url\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/tag\\\/gourmet-honey\\\/\",\"name\":\"gourmet honey archivos - Pico y Tallo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/tag\\\/gourmet-honey\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/tag\\\/gourmet-honey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/home-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"gourmet honey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/\",\"name\":\"Pico y Tallo\",\"description\":\"Productos Gourmet Online\",\"publisher\":{\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/#organization\",\"name\":\"Pico y Tallo\",\"url\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/picoytallo.com\\/wp-content\\/uploads\\/2022\\/03\\/cropped-Productos-gourmet-picotallo.webp\",\"contentUrl\":\"https:\\/\\/picoytallo.com\\/wp-content\\/uploads\\/2022\\/03\\/cropped-Productos-gourmet-picotallo.webp\",\"width\":1194,\"height\":314,\"caption\":\"Pico y Tallo\"},\"image\":{\"@id\":\"https:\\\/\\\/picoytallo.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"gourmet honey archivos - Pico y Tallo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/","og_locale":"en_US","og_type":"article","og_title":"gourmet honey archivos - Pico y Tallo","og_url":"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/","og_site_name":"Pico y Tallo","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/","url":"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/","name":"gourmet honey archivos - Pico y Tallo","isPartOf":{"@id":"https:\/\/picoytallo.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/picoytallo.com\/en\/tag\/gourmet-honey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/picoytallo.com\/en\/home-2\/"},{"@type":"ListItem","position":2,"name":"gourmet honey"}]},{"@type":"WebSite","@id":"https:\/\/picoytallo.com\/en\/#website","url":"https:\/\/picoytallo.com\/en\/","name":"Pico y Tallo","description":"Productos Gourmet Online","publisher":{"@id":"https:\/\/picoytallo.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/picoytallo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/picoytallo.com\/en\/#organization","name":"Pico y Tallo","url":"https:\/\/picoytallo.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/picoytallo.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mls7guyktf6t.i.optimole.com\/w:auto\/h:auto\/q:mauto\/g:sm\/f:best\/https:\/\/picoytallo.com\/wp-content\/uploads\/2022\/03\/cropped-Productos-gourmet-picotallo.webp","contentUrl":"https:\/\/mls7guyktf6t.i.optimole.com\/w:auto\/h:auto\/q:mauto\/g:sm\/f:best\/https:\/\/picoytallo.com\/wp-content\/uploads\/2022\/03\/cropped-Productos-gourmet-picotallo.webp","width":1194,"height":314,"caption":"Pico y Tallo"},"image":{"@id":"https:\/\/picoytallo.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/picoytallo.com\/en\/wp-json\/wp\/v2\/tags\/213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/picoytallo.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/picoytallo.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/picoytallo.com\/en\/wp-json\/wp\/v2\/posts?tags=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}